{"id":723,"count":1,"description":"","link":"https:\/\/mcdowellequipment.com\/es\/category\/equipamiento-forestal\/","name":"Equipamiento forestal","slug":"equipamiento-forestal","taxonomy":"category","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/mcdowellequipment.com\/es\/wp-json\/wp\/v2\/categories\/723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcdowellequipment.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mcdowellequipment.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mcdowellequipment.com\/es\/wp-json\/wp\/v2\/posts?categories=723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}